{"id":542,"count":4,"description":"","link":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/","name":"UUS- Dekoor","slug":"uusdeco-sv","taxonomy":"product-category","parent":129,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UUS- Dekoor - Arens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UUS- Dekoor - Arens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/\" \/>\n<meta property=\"og:site_name\" content=\"Arens\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arens.ee\/wp-content\/uploads\/2021\/12\/arens-social.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/arens.ee\\\/sv\\\/kategooria\\\/uusdeco-sv\\\/\",\"url\":\"https:\\\/\\\/arens.ee\\\/sv\\\/kategooria\\\/uusdeco-sv\\\/\",\"name\":\"UUS- Dekoor - Arens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arens.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arens.ee\\\/sv\\\/kategooria\\\/uusdeco-sv\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arens.ee\\\/sv\\\/kategooria\\\/uusdeco-sv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arens.ee\\\/sv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UUS- Dekoor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arens.ee\\\/#website\",\"url\":\"https:\\\/\\\/arens.ee\\\/\",\"name\":\"Arens\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arens.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UUS- Dekoor - Arens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/","og_locale":"sv_SE","og_type":"article","og_title":"UUS- Dekoor - Arens","og_url":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/","og_site_name":"Arens","og_image":[{"width":1200,"height":627,"url":"https:\/\/arens.ee\/wp-content\/uploads\/2021\/12\/arens-social.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/","url":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/","name":"UUS- Dekoor - Arens","isPartOf":{"@id":"https:\/\/arens.ee\/#website"},"breadcrumb":{"@id":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/#breadcrumb"},"inLanguage":"sv-SE"},{"@type":"BreadcrumbList","@id":"https:\/\/arens.ee\/sv\/kategooria\/uusdeco-sv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arens.ee\/sv\/"},{"@type":"ListItem","position":2,"name":"UUS- Dekoor"}]},{"@type":"WebSite","@id":"https:\/\/arens.ee\/#website","url":"https:\/\/arens.ee\/","name":"Arens","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arens.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"}]}},"_links":{"self":[{"href":"https:\/\/arens.ee\/sv\/wp-json\/wp\/v2\/product-category\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arens.ee\/sv\/wp-json\/wp\/v2\/product-category"}],"about":[{"href":"https:\/\/arens.ee\/sv\/wp-json\/wp\/v2\/taxonomies\/product-category"}],"up":[{"embeddable":true,"href":"https:\/\/arens.ee\/sv\/wp-json\/wp\/v2\/product-category\/129"}],"wp:post_type":[{"href":"https:\/\/arens.ee\/sv\/wp-json\/wp\/v2\/products?product-category=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}